{"id":3294,"date":"2016-07-20T17:39:33","date_gmt":"2016-07-20T17:39:33","guid":{"rendered":"http:\/\/themenectar.com\/demo\/salient-product\/?page_id=2"},"modified":"2026-04-01T15:40:29","modified_gmt":"2026-04-01T15:40:29","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/www.kolpo.it\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\n\t\t<div id=\"fws_6a0488c010b9d\" data-fullscreen-anchor-id=\"intro\" data-column-margin=\"default\" data-midnight=\"light\" data-nectar-animated-gradient-settings=\"{&quot;color_1&quot;:&quot;#ff3a4c&quot;,&quot;color_2&quot;:&quot;&quot;,&quot;speed&quot;:&quot;1300&quot;,&quot;blending_mode&quot;:&quot;linear&quot;}\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Kopo\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap has-animated-gradient\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #000000; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: #000000; background: linear-gradient(90deg,#000000 10%,rgba(255,255,255,0.001) 75%);  opacity: 0.5; background: #000000; background: linear-gradient(90deg,#000000 0%,rgba(255,255,255,0.001) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"nectar-shape-divider-wrap no-color \" style=\" height:50px;\"  data-height=\"50\" data-front=\"\" data-style=\"mountains\" data-position=\"bottom\" ><svg class=\"nectar-shape-divider\" fill=\"\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 300\" preserveAspectRatio=\"none\">\n          <path d=\"M 1014 264 v 122 h -808 l -172 -86 s 310.42 -22.84 402 -79 c 106 -65 154 -61 268 -12 c 107 46 195.11 5.94 275 137 z\"><\/path>   <path d=\"M -302 55 s 235.27 208.25 352 159 c 128 -54 233 -98 303 -73 c 92.68 33.1 181.28 115.19 235 108 c 104.9 -14 176.52 -173.06 267 -118 c 85.61 52.09 145 123 145 123 v 74 l -1306 10 z\"><\/path>\n          <path d=\"M -286 255 s 214 -103 338 -129 s 203 29 384 101 c 145.57 57.91 178.7 50.79 272 0 c 79 -43 301 -224 385 -63 c 53 101.63 -62 129 -62 129 l -107 84 l -1212 12 z\"><\/path>\n          <path d=\"M -24 69 s 299.68 301.66 413 245 c 8 -4 233 2 284 42 c 17.47 13.7 172 -132 217 -174 c 54.8 -51.15 128 -90 188 -39 c 76.12 64.7 118 99 118 99 l -12 132 l -1212 12 z\"><\/path>\n          <path d=\"M -12 201 s 70 83 194 57 s 160.29 -36.77 274 6 c 109 41 184.82 24.36 265 -15 c 55 -27 116.5 -57.69 214 4 c 49 31 95 26 95 26 l -6 151 l -1036 10 z\"><\/path> <\/svg><\/div><div class=\"container\"><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding force-phone-text-align-center top_margin_phone_10pct inherit_tablet no-extra-padding_phone \"  data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_phone_15px \" data-align=\"center\" data-m-align=\"center\" data-text-effect=\"twist-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"true\" style=\"font-size: 30px; line-height: 32.4px;\"><h1 >Attrezzatura e accessori da Pesca<\/h1><\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"226\" width=\"2560\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-scaled.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-scaled.png 2560w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-300x26.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-1024x90.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-768x68.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-1536x135.png 1536w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-2048x181.png 2048w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/logo-kolpo-rosso-18x2.png 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: center;\">Passione, tecnica, evoluzione. Da sempre il nostro impegno \u00e8 orientato alla ricerca e all\u2019innovazione, con l\u2019obiettivo di offrire agli appassionati di pesca sportiva strumenti affidabili, performanti e dal valore reale.<\/p>\n<p style=\"text-align: center;\">Ogni nuova stagione rappresenta per noi una sfida: migliorare costantemente, evolvere nei materiali, affinare i dettagli, testare sul campo ogni prodotto per garantire qualit\u00e0 e concretezza.<\/p>\n<p style=\"text-align: center;\">Il mondo Kolpo \u00e8 fatto di passione, di persone che credono nel progetto e di pescatori che ogni giorno scelgono la nostra esperienza. A loro, clienti, collaboratori e partner va il nostro grazie sincero, perch\u00e9 \u00e8 anche grazie alla vostra fiducia che continuiamo a crescere e a innovare.<br \/>\nBenvenuti nel mondo Kolpo.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"489\" width=\"1709\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3.png 1709w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3-300x86.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3-1024x293.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3-768x220.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3-1536x439.png 1536w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Senza-titolo-3-18x5.png 18w\" sizes=\"auto, (max-width: 1709px) 100vw, 1709px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding force-phone-text-align-center inherit_tablet no-extra-padding_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c011163\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet no-extra-padding_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"700\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"423\" width=\"1024\" data-animation=\"fade-in\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-sito.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-sito.jpg 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-sito-300x124.jpg 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-sito-768x317.jpg 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-sito-18x7.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"1687\" width=\"2405\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata.jpg 2405w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-300x210.jpg 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-1024x718.jpg 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-768x539.jpg 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-1536x1077.jpg 1536w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-2048x1437.jpg 2048w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiata-18x12.jpg 18w\" sizes=\"auto, (max-width: 2405px) 100vw, 2405px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c01146c\" data-fullscreen-anchor-id=\"agenti\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Agenti\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-12-percent inherit_tablet padding-1-percent_phone \"  data-padding-pos=\"left-right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c0114ef\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column centered-text has-animation no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3 style=\"text-align: center;\"><strong>KOLPO RICERCA AGENTI IN ITALIA INVIA LA TUA CANDIDATURA!<\/strong><\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"800\" width=\"800\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3.jpg 800w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-300x300.jpg 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-150x150.jpg 150w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-768x768.jpg 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-12x12.jpg 12w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-100x100.jpg 100w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-140x140.jpg 140w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-500x500.jpg 500w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/04\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-3-350x350.jpg 350w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"768\" width=\"768\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-768x768.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-768x768.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-300x300.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-1024x1024.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-150x150.png 150w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-12x12.png 12w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-100x100.png 100w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-140x140.png 140w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-500x500.png 500w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-350x350.png 350w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-1000x1000.png 1000w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5-800x800.png 800w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-5.png 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3 style=\"text-align: center;\"><strong>WE ARE LOOKING FOR AGENTS ACROSS EUROPE. CONTACT US!<\/strong><\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"1080\" width=\"1080\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2.png 1080w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-300x300.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-1024x1024.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-150x150.png 150w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-768x768.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-12x12.png 12w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-100x100.png 100w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-140x140.png 140w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-500x500.png 500w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-350x350.png 350w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-1000x1000.png 1000w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-800x800.png 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c0119c5\" data-fullscreen-anchor-id=\"mulinelli\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Mulinelli\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-11-percent inherit_tablet padding-1-percent_phone \"  data-padding-pos=\"left-right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c011a58\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text has-animation no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2 style=\"text-align: center;\">Il Mondo Della Pesca Firmato Kolpo<\/h2>\n<h3 style=\"text-align: center;\">Con <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Kolpo<\/span><\/span> vivi la pesca a 360\u00b0: un\u2019ampia gamma di attrezzature pensate per mare e acque interne, ideali per tecniche come feeder, eging, surfcasting, bolentino, bolognese, spinning, carp fishing, trout area, pesca a fondo, traina e pesca al colpo.<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a0488c011b27\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SURF-kolpo.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SURF-kolpo.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SURF-kolpo-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SURF-kolpo-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/PASTURA-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/PASTURA-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/PASTURA-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/PASTURA-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/AMI-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/AMI-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/AMI-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/AMI-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/egi-kolpo.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/egi-kolpo.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/egi-kolpo-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/egi-kolpo-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/soft-lures-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/soft-lures-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/soft-lures-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/soft-lures-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/POPPER-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/POPPER-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/POPPER-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/POPPER-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MAGIC-TUNA-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MAGIC-TUNA-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MAGIC-TUNA-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MAGIC-TUNA-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/CARP-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/CARP-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/CARP-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/CARP-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/FILI-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/FILI-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/FILI-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/FILI-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SPIN-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SPIN-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SPIN-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MUL-SPIN-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/GALASSIA-KLP.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/GALASSIA-KLP.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/GALASSIA-KLP-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/GALASSIA-KLP-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"629\" width=\"592\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/TOTANARE-KOLPO.jpg\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/TOTANARE-KOLPO.jpg 592w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/TOTANARE-KOLPO-282x300.jpg 282w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/TOTANARE-KOLPO-11x12.jpg 11w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c0127c2\" data-fullscreen-anchor-id=\"specs\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Specifiche Tecniche\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"container\"><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col padding-2-percent inherit_tablet inherit_phone \"  data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: center;\">NEW FISHING ROD TECHNOLOGY<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"1024\" width=\"742\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-742x1024.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-742x1024.png 742w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-218x300.png 218w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-768x1059.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-1114x1536.png 1114w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-1485x2048.png 1485w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-9x12.png 9w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-MATERIALS-scaled.png 1856w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: center;\">ADVANCED TECHNOLOGY FOR EGI<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"1024\" width=\"762\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-762x1024.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-762x1024.png 762w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-223x300.png 223w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-768x1031.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-1144x1536.png 1144w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-1525x2048.png 1525w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-9x12.png 9w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-totanare-1-scaled.png 1906w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: center;\">NEW REEL TECHNOLOGY<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"1024\" width=\"748\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-748x1024.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-748x1024.png 748w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-219x300.png 219w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-768x1051.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-1123x1536.png 1123w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-1497x2048.png 1497w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-9x12.png 9w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/kolpo-mulinelli-scaled.png 1871w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c012cdc\" data-fullscreen-anchor-id=\"catalogo\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Catalogo Kolpo\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding force-desktop-text-align-center inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c012d6a\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  right_padding_5pct left_padding_5pct top_padding_phone_5pct right_padding_phone_2pct left_padding_phone_2pct\"  style=\"padding-top: 5%; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text has-animation no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2 style=\"text-align: center;\">Sfoglia il catalogo kolpo 2026<\/h2>\n<h3 style=\"text-align: center;\">Benvenuti nel nuovo catalogo Kolpo 2026.<br \/>\nUn anno di nuove idee, nuovi orizzonti e la stessa autentica passione di sempre.<br \/>\nUn sincero grazie a tutti!<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a0488c012e46\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column padding-1-percent inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\" data-hover-animation=\"zoom-crop\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.kolpo.it\/shop\/img\/CATALOGO-KOLPO-2026-WEB.pdf\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"211\" width=\"1024\" data-animation=\"fade-in\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-1024x211.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-1024x211.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-300x62.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-768x159.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-1536x317.png 1536w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-2048x423.png 2048w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/KOLPO-CATALOGO-2026-18x4.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c01308b\" data-fullscreen-anchor-id=\"video\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"video\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c013110\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  right_padding_5pct left_padding_5pct top_padding_phone_10pct right_padding_phone_2pct left_padding_phone_2pct\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text has-animation no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1664981228059\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>Video Attrezzatura da pesca Kolpo<\/h2>\n<h3><span style=\"color: #999999;\">Kolpo produce e commercializza la migliore attrezzatura per la pesca. Il nostro Team segue in maniera maniacale ogni fase della progettazione e tutta la fase della produzione. Canne, Mulinelli e accessori vengono tutti uno ad uno controllati e testati. Il Rigido cotrollo qualit\u00e0 ci permette di offrirVi prodotti di alta gamma, perfetti e curati in ogni minimo particolare al prezzo pi\u00f9 basso di mercato.<\/span><\/h3>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a0488c0131e9\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_video_player_self_hosted wpb_video_widget wpb_content_element vc_clearfix vc_video-aspect-ratio-916 vc_video-el-width-70 vc_video-align-center\" data-border-radius=\"none\" data-shadow=\"none\">\n<div class=\"wpb_wrapper\"><div class=\"wpb_video_wrapper\"><video width=\"1280\" height=\"720\" class=\"nectar-video-self-hosted\" preload=\"metadata\" controls controlsList=\"nodownload\" poster=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/seppia.jpg\"><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MicrosoftTeams-video.mp4\" type=\"video\/webm\"><\/video><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_video_player_self_hosted wpb_video_widget wpb_content_element vc_clearfix vc_video-aspect-ratio-916 vc_video-el-width-70 vc_video-align-center\" data-border-radius=\"none\" data-shadow=\"none\">\n<div class=\"wpb_wrapper\"><div class=\"wpb_video_wrapper\"><video width=\"1280\" height=\"720\" class=\"nectar-video-self-hosted\" preload=\"metadata\" controls controlsList=\"nodownload\" poster=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/rod-rest.jpg\"><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/copy_A483EC6F-75C6-4BCF-B4AB-B02D75835E79.mov\" type=\"video\/webm\"><\/video><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_video_player_self_hosted wpb_video_widget wpb_content_element vc_clearfix vc_video-aspect-ratio-916 vc_video-el-width-70 vc_video-align-center\" data-border-radius=\"none\" data-shadow=\"none\">\n<div class=\"wpb_wrapper\"><div class=\"wpb_video_wrapper\"><video width=\"1280\" height=\"720\" class=\"nectar-video-self-hosted\" preload=\"metadata\" controls controlsList=\"nodownload\" poster=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/occhiali.jpg\"><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/copy_4C83C101-A5CA-47E4-A30F-B90B484C4D31-2.mov\" type=\"video\/webm\"><\/video><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_video_player_self_hosted wpb_video_widget wpb_content_element vc_clearfix vc_video-aspect-ratio-916 vc_video-el-width-70 vc_video-align-center\" data-border-radius=\"none\" data-shadow=\"none\">\n<div class=\"wpb_wrapper\"><div class=\"wpb_video_wrapper\"><video width=\"1280\" height=\"720\" class=\"nectar-video-self-hosted\" preload=\"metadata\" controls controlsList=\"nodownload\" poster=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/veilo.jpg\"><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/MicrosoftTeams-video-1.mp4\" type=\"video\/webm\"><\/video><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c013629\" data-fullscreen-anchor-id=\"industria\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  top_padding_tablet_20pct top_padding_phone_20pct bottom_padding_tablet_20pct bottom_padding_phone_20pct\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Industria\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"container\"><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c0136b3\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \" data-cfc=\"true\"  data-padding-pos=\"bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1666689228699\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h5>Industria 4.0<\/h5>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"nectar-split-heading \" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\"max-width: 475px;\">Kolpo utilizza scaffali intelligenti verticali per lo stoccaggio delle merci semplificando tutte le operazioni di magazzino e risparmiare notevolmente spazio a terra, con questa nuova tecnologia abbinata al sistema put to light riusciamo a velocizzare il picking ridurre drasticamente la possibilit\u00e0 di errore ed evadere i Vostri ordini in 24\/48 ore<\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation padding-4-percent inherit_tablet inherit_phone \"  data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar_video_player_self_hosted wpb_video_widget wpb_content_element vc_clearfix vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" data-border-radius=\"10px\" data-shadow=\"none\">\n<div class=\"wpb_wrapper\"><div class=\"wpb_video_wrapper\"><video width=\"1280\" height=\"720\" class=\"nectar-video-self-hosted scroll-triggered-play\" preload=\"auto\" loop  muted playsinline><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2022\/10\/kolpo-pesca.mp4\" type=\"video\/webm\"><source src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2022\/10\/kolpo-pesca.mp4\"  type=\"video\/mp4\"><\/video><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n\t\t<div id=\"fws_6a0488c0138c9\" data-fullscreen-anchor-id=\"contatti\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  zindex-set\"  style=\"\"><div class=\"full-page-inner-wrap-outer\"><div class=\"full-page-inner-wrap\" data-name=\"Contatti\" data-content-pos=\"middle\"><div class=\"full-page-inner\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(173,173,173,0.93); background: linear-gradient(135deg,rgba(173,173,173,0.93) 0%,rgba(255,255,255,0.92) 100%);  opacity: 0.95; \"><\/div><\/div><div class=\"container\"><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col centered-text no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>Contattaci per informazioni<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col centered-text no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap center custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: 10%; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"300\" width=\"300\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-300x300.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-300x300.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-1024x1024.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-150x150.png 150w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-768x768.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-12x12.png 12w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-100x100.png 100w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-140x140.png 140w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-500x500.png 500w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-350x350.png 350w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-1000x1000.png 1000w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1-800x800.png 800w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-1.png 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div><div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"300\" width=\"300\" data-animation=\"none\" src=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-300x300.png\" alt=\"\" srcset=\"https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-300x300.png 300w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-1024x1024.png 1024w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-150x150.png 150w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-768x768.png 768w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-12x12.png 12w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-100x100.png 100w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-140x140.png 140w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-500x500.png 500w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-350x350.png 350w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-1000x1000.png 1000w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2-800x800.png 800w, https:\/\/www.kolpo.it\/wp-content\/uploads\/2026\/03\/Green-Modern-Job-Vacation-and-Hiring-Instagram-Post-2.png 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0488c013bda\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"padding-top: 10%; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div class='fluentform ff-default fluentform_wrapper_1 ffs_default_wrap'><form data-form_id=\"1\" id=\"fluentform_1\" class=\"frm-fluent-form fluent_form_1 ff-el-form-top ff_form_instance_1_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_1_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Contact Form Demo<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='3294' \/><input type=\"hidden\" id=\"_fluentform_1_fluentformnonce\" name=\"_fluentform_1_fluentformnonce\" value=\"38d590e75a\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/3294\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_names_first_name_' id='label_ff_1_names_first_name_' >Nome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_1_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Nome\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_names_last_name_' id='label_ff_1_names_last_name_' >Cognome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_1_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Cognome\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email' id='label_ff_1_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_1_email\" class=\"ff-el-form-control\" placeholder=\"Indirizzo Email\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_subject' id='label_ff_1_subject' aria-label=\"Oggetto\">Oggetto<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"subject\" class=\"ff-el-form-control\" placeholder=\"Oggetto\" data-name=\"subject\" id=\"ff_1_subject\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_message' id='label_ff_1_message' aria-label=\"Messaggio\">Messaggio<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_1_message\" name=\"message\" id=\"ff_1_message\" class=\"ff-el-form-control\" placeholder=\"Lascia qui il tuo Messaggio\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Invia Messaggio\">Invia Messaggio<\/button><\/div><\/fieldset><\/form><div id='fluentform_1_errors' class='ff-errors-in-stack ff_form_instance_1_1 ff-form-loading_errors ff_form_instance_1_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_1_1 = {\"id\":\"1\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_1_1\",\"form_id_selector\":\"fluentform_1\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Campo richiesto obbligatorio\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Campo richiesto obbligatorio\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Campo richiesto obbligatorio\"},\"email\":{\"value\":true,\"message\":\"Email non valida\"}},\"subject\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"message\":{\"required\":{\"value\":true,\"message\":\"Campo richiesto obbligatorio\"}}},\"debounce_time\":300};\n                            <\/script>\n            \n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><\/div><!--inner-wrap-->\n","protected":false},"excerpt":{"rendered":"Attrezzatura e accessori da Pesca Passione, tecnica, evoluzione. Da sempre il nostro impegno \u00e8 orientato alla ricerca e all\u2019innovazione, con l\u2019obiettivo di offrire agli appassionati di pesca sportiva strumenti affidabili,...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3294","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/pages\/3294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/comments?post=3294"}],"version-history":[{"count":182,"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/pages\/3294\/revisions"}],"predecessor-version":[{"id":3685,"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/pages\/3294\/revisions\/3685"}],"wp:attachment":[{"href":"https:\/\/www.kolpo.it\/en\/wp-json\/wp\/v2\/media?parent=3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}